{"id":100100,"date":"2026-03-12T08:48:04","date_gmt":"2026-03-12T08:48:04","guid":{"rendered":"https:\/\/www.eelectron.com\/prodotti\/modulo-din-universal-8-IN-alta-tension-100-250-v-ca-cc\/"},"modified":"2026-08-03T14:55:35","modified_gmt":"2026-08-03T14:55:35","slug":"modulo-din-universal-8-entradas-alta-tension-100-250-v-ca-cc","status":"publish","type":"product-family","link":"https:\/\/www.eelectron.com\/es\/productos\/modulo-din-universal-8-entradas-alta-tension-100-250-v-ca-cc\/","title":{"rendered":"M\u00f3dulo DIN universal 8 ENTRADAS &#8211; Alta tensi\u00f3n 100-250 V CA\/CC"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<p>El dispositivo BI08H01KNX tiene 8 ENTRADAS para voltaje de 100 a 230 VAC.<br \/>Permite detectar tanto estados de voltaje (presentes o ausentes) como cambios en los estados\/pulsos de voltaje.<\/p>\n<p>Puede utilizarse, por ejemplo, para monitorizar tensiones de red, detectar estados de conmutaci\u00f3n o del sistema, detectar un cambio de estado al encender o apagar una tensi\u00f3n (si se ha accionado un interruptor o bot\u00f3n), o m\u00e1s simplemente para las funciones cl\u00e1sicas de l\u00e1mparas encendido\/apagado\/atenuante o control de persianas.<\/p>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":true},"product-family-category":[409,410,419],"product-family-tags":[],"class_list":["post-100100","product-family","type-product-family","status-publish","hentry","product-family-category-actuadores","product-family-category-actuadores-de-barra-din","product-family-category-entradas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00f3dulo DIN universal 8 pulgadas - Alta tensi\u00f3n 100-250 V AC\/DC - Eelectron<\/title>\n<meta name=\"description\" content=\"M\u00f3dulo DIN universal de 8 pulgadas - alta tensi\u00f3n 100-250 V AC\/CC. Actuadores modulares para ra\u00edles DIN: conmutaci\u00f3n, control de carga y gesti\u00f3n de carga para gabinete de control profesional \u2014 solicita hoja t\u00e9cnica y curvas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eelectron.com\/es\/productos\/modulo-din-universal-8-entradas-alta-tension-100-250-v-ca-cc\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00f3dulo DIN universal 8 pulgadas - Alta tensi\u00f3n 100-250 V AC\/DC - Eelectron\" \/>\n<meta property=\"og:description\" content=\"M\u00f3dulo DIN universal de 8 pulgadas - alta tensi\u00f3n 100-250 V AC\/CC. Actuadores modulares para ra\u00edles DIN: conmutaci\u00f3n, control de carga y gesti\u00f3n de carga para gabinete de control profesional \u2014 solicita hoja t\u00e9cnica y curvas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eelectron.com\/es\/productos\/modulo-din-universal-8-entradas-alta-tension-100-250-v-ca-cc\/\" \/>\n<meta property=\"og:site_name\" content=\"eelectron - website\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-03T14:55:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eelectron.com\\\/es\\\/productos\\\/modulo-din-universal-8-entradas-alta-tension-100-250-v-ca-cc\\\/\",\"url\":\"https:\\\/\\\/www.eelectron.com\\\/es\\\/productos\\\/modulo-din-universal-8-entradas-alta-tension-100-250-v-ca-cc\\\/\",\"name\":\"M\u00f3dulo DIN universal 8 pulgadas - Alta tensi\u00f3n 100-250 V AC\\\/DC - Eelectron\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eelectron.com\\\/es\\\/#website\"},\"datePublished\":\"2026-03-12T08:48:04+00:00\",\"dateModified\":\"2026-08-03T14:55:35+00:00\",\"description\":\"M\u00f3dulo DIN universal de 8 pulgadas - alta tensi\u00f3n 100-250 V AC\\\/CC. Actuadores modulares para ra\u00edles DIN: conmutaci\u00f3n, control de carga y gesti\u00f3n de carga para gabinete de control profesional \u2014 solicita hoja t\u00e9cnica y curvas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eelectron.com\\\/es\\\/productos\\\/modulo-din-universal-8-entradas-alta-tension-100-250-v-ca-cc\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eelectron.com\\\/es\\\/productos\\\/modulo-din-universal-8-entradas-alta-tension-100-250-v-ca-cc\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eelectron.com\\\/es\\\/productos\\\/modulo-din-universal-8-entradas-alta-tension-100-250-v-ca-cc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.eelectron.com\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00f3dulo DIN universal 8 ENTRADAS &#8211; Alta tensi\u00f3n 100-250 V CA\\\/CC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eelectron.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.eelectron.com\\\/es\\\/\",\"name\":\"Eelectron\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eelectron.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eelectron.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eelectron.com\\\/es\\\/#organization\",\"name\":\"Eelectron\",\"url\":\"https:\\\/\\\/www.eelectron.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.eelectron.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.eelectron.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-1.png\",\"contentUrl\":\"https:\\\/\\\/www.eelectron.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-1.png\",\"width\":200,\"height\":40,\"caption\":\"Eelectron\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eelectron.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00f3dulo DIN universal 8 pulgadas - Alta tensi\u00f3n 100-250 V AC\/DC - Eelectron","description":"M\u00f3dulo DIN universal de 8 pulgadas - alta tensi\u00f3n 100-250 V AC\/CC. Actuadores modulares para ra\u00edles DIN: conmutaci\u00f3n, control de carga y gesti\u00f3n de carga para gabinete de control profesional \u2014 solicita hoja t\u00e9cnica y curvas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eelectron.com\/es\/productos\/modulo-din-universal-8-entradas-alta-tension-100-250-v-ca-cc\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00f3dulo DIN universal 8 pulgadas - Alta tensi\u00f3n 100-250 V AC\/DC - Eelectron","og_description":"M\u00f3dulo DIN universal de 8 pulgadas - alta tensi\u00f3n 100-250 V AC\/CC. Actuadores modulares para ra\u00edles DIN: conmutaci\u00f3n, control de carga y gesti\u00f3n de carga para gabinete de control profesional \u2014 solicita hoja t\u00e9cnica y curvas.","og_url":"https:\/\/www.eelectron.com\/es\/productos\/modulo-din-universal-8-entradas-alta-tension-100-250-v-ca-cc\/","og_site_name":"eelectron - website","article_modified_time":"2026-08-03T14:55:35+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.eelectron.com\/es\/productos\/modulo-din-universal-8-entradas-alta-tension-100-250-v-ca-cc\/","url":"https:\/\/www.eelectron.com\/es\/productos\/modulo-din-universal-8-entradas-alta-tension-100-250-v-ca-cc\/","name":"M\u00f3dulo DIN universal 8 pulgadas - Alta tensi\u00f3n 100-250 V AC\/DC - Eelectron","isPartOf":{"@id":"https:\/\/www.eelectron.com\/es\/#website"},"datePublished":"2026-03-12T08:48:04+00:00","dateModified":"2026-08-03T14:55:35+00:00","description":"M\u00f3dulo DIN universal de 8 pulgadas - alta tensi\u00f3n 100-250 V AC\/CC. Actuadores modulares para ra\u00edles DIN: conmutaci\u00f3n, control de carga y gesti\u00f3n de carga para gabinete de control profesional \u2014 solicita hoja t\u00e9cnica y curvas.","breadcrumb":{"@id":"https:\/\/www.eelectron.com\/es\/productos\/modulo-din-universal-8-entradas-alta-tension-100-250-v-ca-cc\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eelectron.com\/es\/productos\/modulo-din-universal-8-entradas-alta-tension-100-250-v-ca-cc\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eelectron.com\/es\/productos\/modulo-din-universal-8-entradas-alta-tension-100-250-v-ca-cc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.eelectron.com\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"M\u00f3dulo DIN universal 8 ENTRADAS &#8211; Alta tensi\u00f3n 100-250 V CA\/CC"}]},{"@type":"WebSite","@id":"https:\/\/www.eelectron.com\/es\/#website","url":"https:\/\/www.eelectron.com\/es\/","name":"Eelectron","description":"","publisher":{"@id":"https:\/\/www.eelectron.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eelectron.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.eelectron.com\/es\/#organization","name":"Eelectron","url":"https:\/\/www.eelectron.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.eelectron.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.eelectron.com\/wp-content\/uploads\/2025\/05\/logo-1.png","contentUrl":"https:\/\/www.eelectron.com\/wp-content\/uploads\/2025\/05\/logo-1.png","width":200,"height":40,"caption":"Eelectron"},"image":{"@id":"https:\/\/www.eelectron.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.eelectron.com\/es\/wp-json\/wp\/v2\/product-family\/100100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eelectron.com\/es\/wp-json\/wp\/v2\/product-family"}],"about":[{"href":"https:\/\/www.eelectron.com\/es\/wp-json\/wp\/v2\/types\/product-family"}],"wp:attachment":[{"href":"https:\/\/www.eelectron.com\/es\/wp-json\/wp\/v2\/media?parent=100100"}],"wp:term":[{"taxonomy":"product-family-category","embeddable":true,"href":"https:\/\/www.eelectron.com\/es\/wp-json\/wp\/v2\/product-family-category?post=100100"},{"taxonomy":"product-family-tags","embeddable":true,"href":"https:\/\/www.eelectron.com\/es\/wp-json\/wp\/v2\/product-family-tags?post=100100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}